{"id":10,"date":"2013-02-05T11:37:41","date_gmt":"2013-02-05T09:37:41","guid":{"rendered":"http:\/\/docsites.cgmlife.com\/medistar\/?page_id=10"},"modified":"2023-11-16T17:06:13","modified_gmt":"2023-11-16T15:06:13","slug":"impressum-datenschutzhinweise","status":"publish","type":"page","link":"https:\/\/docsites.cgmlife.com\/147325057143\/impressum-datenschutzhinweise\/","title":{"rendered":"Impressum &amp; Datenschutzhinweise"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><th>Name und Anschrift:<\/th><td>Dr. med. Carsten Rottmann<br>Stadthallenweg 1<br>35315 Homberg\/Ohm<br>Fon: 06633 \/ 235<br>Fax: 06633 \/ 643515<\/td><\/tr><tr><th>E-mail-Adresse:<\/th><td>hausarzt-homberg@t-online.de<\/td><\/tr><tr><th>\u00c4rztekammer des Arztes:<\/th><td>Landes\u00e4rztekammer Hessen<br>Hanauer Landstra\u00dfe 152, 60314 Frankfurt<br>Postfach 900669, 60446 Frankfurt\/Main<br>Telefon: (069) 97672-0<br>Fax: (069) 97672-128<br>E-Mail: info@laekh.de<\/td><\/tr><tr><th>KV des Arztes:<\/th><td>KV Gie\u00dfen eV.<br>Eichg\u00e4rtenallee 90, 35394 Gie\u00dfen<br>Telefon:0641\/400060<br>Telefax:0641\/4000660<br>KV-Nummer: 41 19 019 00<\/td><\/tr><tr><th>Gesetzliche Berufsbezeichnung:<\/th><td>Arzt, verliehen in der Bundesrepublik Deutschland<\/td><\/tr><tr><th>Berufsordnung:<\/th><td>Siehe Webseite der Landes\u00e4rztekammer Hessen <a href=\"http:\/\/www.laekh.de\/\" target=\"_blank\" rel=\"noopener\">www.laekh.de<\/a><br><br>oder <a href=\"https:\/\/www.laekh.de\/fileadmin\/user_upload\/Aerzte\/Rund_ums_Recht\/Rechtsquellen\/Berufsordnung.pdf\">https:\/\/www.laekh.de\/fileadmin\/user_upload\/Aerzte\/Rund_ums_Recht\/Rechtsquellen\/Berufsordnung.pdf<\/a><br><br><a href=\"https:\/\/www.laekh.de\/fileadmin\/user_upload\/Aerzte\/Rund_ums_Recht\/Rechtsquellen\/Heilberufsgesetz.pdf\">https:\/\/www.laekh.de\/fileadmin\/user_upload\/Aerzte\/Rund_ums_Recht\/Rechtsquellen\/Heilberufsgesetz.pdf<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Wir \u00fcbernehmen keine Haftung f\u00fcr die Inhalte externer Links.<br>F\u00fcr den Inhalt der verlinkten Seiten sind ausschlie\u00dflich die Betreiber verantwortlich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Datenschutzerkl\u00e4rung<\/strong><\/h2>\n\n\n\n<p>Eine Nutzung unserer Internetseiten&nbsp; ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten erforderlich werden. Ist die Verarbeitung personenbezogener Daten erforderlich und besteht f\u00fcr eine solche Verarbeitung keine gesetzliche Grundlage, holen wir generell eine Einwilligung der betroffenen Person ein.Die Verarbeitung personenbezogener Daten, beispielsweise des Namens, der Anschrift, E-Mail-Adresse oder Telefonnummer einer betroffenen Person, erfolgt stets im Einklang mit der Datenschutz-Grundverordnung und in \u00dcbereinstimmung mit den f\u00fcr die Arztpraxis Dr. med. Carsten Rottmann geltenden landesspezifischen Datenschutzbestimmungen. Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte unser Unternehmen die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der von uns erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. Ferner werden betroffene Personen mittels dieser Datenschutzerkl\u00e4rung \u00fcber die ihnen zustehenden Rechte aufgekl\u00e4rt. Die Arztpraxis Dr. med. Carsten Rottmann hat als f\u00fcr die Verarbeitung Verantwortlicher zahlreiche technische und organisatorische Ma\u00dfnahmen umgesetzt, um einen m\u00f6glichst l\u00fcckenlosen Schutz der \u00fcber diese Internetseite verarbeiteten personenbezogenen Daten sicherzustellen. Dennoch k\u00f6nnen Internetbasierte Daten\u00fcbertragungen grunds\u00e4tzlich Sicherheitsl\u00fccken aufweisen, sodass ein absoluter Schutz nicht gew\u00e4hrleistet werden kann. Aus diesem Grund steht es jeder betroffenen Person frei, personenbezogene Daten auch auf alternativen Wegen, beispielsweise telefonisch, an uns zu \u00fcbermitteln.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Begriffsbestimmungen<\/strong><\/h3>\n\n\n\n<p>Die Datenschutzerkl\u00e4rung der Arztpraxis Dr. med. Carsten Rottmann beruht auf den Begrifflichkeiten, die durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber beim Erlass der Datenschutz-Grundverordnung (DS-GVO) verwendet wurden. Unsere Datenschutzerkl\u00e4rung soll sowohl f\u00fcr die \u00d6ffentlichkeit als auch f\u00fcr unsere Kunden und Gesch\u00e4ftspartner einfach lesbar und verst\u00e4ndlich sein. Um dies zu gew\u00e4hrleisten, m\u00f6chten wir vorab die verwendeten Begrifflichkeiten erl\u00e4utern.<br>Wir verwenden in dieser Datenschutzerkl\u00e4rung unter anderem die folgenden Begriffe:<\/p>\n\n\n\n<p>a) personenbezogene Daten<br>Personenbezogene Daten sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen. Als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind, identifiziert werden kann.<\/p>\n\n\n\n<p>b) betroffene Person<br>Betroffene Person ist jede identifizierte oder identifizierbare nat\u00fcrliche Person, deren personenbezogene Daten von dem f\u00fcr die Verarbeitung Verantwortlichen verarbeitet werden.<\/p>\n\n\n\n<p>c) Verarbeitung<br>Verarbeitung ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/p>\n\n\n\n<p>d) Einschr\u00e4nkung der Verarbeitung<br>Einschr\u00e4nkung der Verarbeitung ist die Markierung gespeicherter personenbezogener Daten mit dem Ziel, ihre k\u00fcnftige Verarbeitung einzuschr\u00e4nken.<\/p>\n\n\n\n<p>e) Profiling<br>Profiling ist jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen, zu bewerten, insbesondere, um Aspekte bez\u00fcglich Arbeitsleistung, wirtschaftlicher Lage, Gesundheit, pers\u00f6nlicher Vorlieben, Interessen, Zuverl\u00e4ssigkeit, Verhalten, Aufenthaltsort oder Ortswechsel dieser nat\u00fcrlichen Person zu analysieren oder vorherzusagen.<\/p>\n\n\n\n<p>f) Pseudonymisierung<br>Pseudonymisierung ist die Verarbeitung personenbezogener Daten in einer Weise, auf welche die personenbezogenen Daten ohne Hinzuziehung zus\u00e4tzlicher Informationen nicht mehr einer spezifischen betroffenen Person zugeordnet werden k\u00f6nnen, sofern diese zus\u00e4tzlichen Informationen gesondert aufbewahrt werden und technischen und organisatorischen Ma\u00dfnahmen unterliegen, die gew\u00e4hrleisten, dass die personenbezogenen Daten nicht einer identifizierten oder identifizierbaren nat\u00fcrlichen Person zugewiesen werden.<\/p>\n\n\n\n<p>g) Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher<br>Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher ist die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet. Sind die Zwecke und Mittel dieser Verarbeitung durch das Unionsrecht oder das Recht der Mitgliedstaaten vorgegeben, so kann der Verantwortliche beziehungsweise k\u00f6nnen die bestimmten Kriterien seiner Benennung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten vorgesehen werden.<\/p>\n\n\n\n<p>h) Auftragsverarbeiter<br>Auftragsverarbeiter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die personenbezogene Daten im Auftrag des Verantwortlichen verarbeitet.<\/p>\n\n\n\n<p>i) Empf\u00e4nger<br>Empf\u00e4nger ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, der personenbezogene Daten offengelegt werden, unabh\u00e4ngig davon, ob es sich bei ihr um einen Dritten handelt oder nicht. Beh\u00f6rden, die im Rahmen eines bestimmten Untersuchungsauftrags nach dem Unionsrecht oder dem Recht der Mitgliedstaaten m\u00f6glicherweise personenbezogene Daten erhalten, gelten jedoch nicht als Empf\u00e4nger.<\/p>\n\n\n\n<p>j) Dritter<br>Dritter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle au\u00dfer der betroffenen Person, dem Verantwortlichen, dem Auftragsverarbeiter und den Personen, die unter der unmittelbaren Verantwortung des Verantwortlichen oder des Auftragsverarbeiters befugt sind, die personenbezogenen Daten zu verarbeiten.<\/p>\n\n\n\n<p>k) Einwilligung<br>Einwilligung ist jede von der betroffenen Person freiwillig f\u00fcr den bestimmten Fall in informierter Weise und unmissverst\u00e4ndlich abgegebene Willensbekundung in Form einer Erkl\u00e4rung oder einer sonstigen eindeutigen best\u00e4tigenden Handlung, mit der die betroffene Person zu verstehen gibt, dass sie mit der Verarbeitung der sie betreffenden personenbezogenen Daten einverstanden ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Name und Anschrift des f\u00fcr die Verarbeitung Verantwortlichen<\/strong><\/h3>\n\n\n\n<p>Verantwortlicher im Sinne der Datenschutz-Grundverordnung, sonstiger in den Mitgliedstaaten der Europ\u00e4ischen Union geltenden Datenschutzgesetze und anderer Bestimmungen mit datenschutzrechtlichem Charakter ist:<\/p>\n\n\n\n<p>Arztpraxis<br>Dr. med. Carsten Rottmann<br>Stadthallenweg 1<br>35315 Homberg\/Ohm<br>Tel.: 0 66 33 \/ 235<br>Fax.: 0 66 33 \/ 643515<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Cookies<\/strong><\/h3>\n\n\n\n<p>Die Internetseiten der Arztpraxis Dr. med. Carsten Rottmann verwenden Cookies. Cookies sind Textdateien, welche \u00fcber einen Internetbrowser auf einem Computersystem abgelegt und gespeichert werden.<br>Zahlreiche Internetseiten und Server verwenden Cookies. Viele Cookies enthalten eine sogenannte Cookie-ID. Eine Cookie-ID ist eine eindeutige Kennung des Cookies. Sie besteht aus einer Zeichenfolge, durch welche Internetseiten und Server dem konkreten Internetbrowser zugeordnet werden k\u00f6nnen, in dem das Cookie gespeichert wurde. Dies erm\u00f6glicht es den besuchten Internetseiten und Servern, den individuellen Browser der betroffenen Person von anderen Internetbrowsern, die andere Cookies enthalten, zu unterscheiden. Ein bestimmter Internetbrowser kann \u00fcber die eindeutige Cookie-ID wiedererkannt und identifiziert werden.<br>Durch den Einsatz von Cookies kann die Arztpraxis Dr. med. Carsten Rottmann den Nutzern dieser Internetseite nutzerfreundlichere Services bereitstellen, die ohne die Cookie-Setzung nicht m\u00f6glich w\u00e4ren.<br>Mittels eines Cookies k\u00f6nnen die Informationen und Angebote auf unserer Internetseite im Sinne des Benutzers optimiert werden. Cookies erm\u00f6glichen uns, wie bereits erw\u00e4hnt, die Benutzer unserer Internetseite wiederzuerkennen. Zweck dieser Wiedererkennung ist es, den Nutzern die Verwendung unserer Internetseite zu erleichtern. Der Benutzer einer Internetseite, die Cookies verwendet, muss beispielsweise nicht bei jedem Besuch der Internetseite erneut seine Zugangsdaten eingeben, weil dies von der Internetseite und dem auf dem Computersystem des Benutzers abgelegten Cookie \u00fcbernommen wird. Ein weiteres Beispiel ist das Cookie eines Warenkorbes im Online-Shop. Der Online-Shop merkt sich die Artikel, die ein Kunde in den virtuellen Warenkorb gelegt hat, \u00fcber ein Cookie.<br>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Ferner k\u00f6nnen bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden. Dies ist in allen g\u00e4ngigen Internetbrowsern m\u00f6glich. Deaktiviert die betroffene Person die Setzung von Cookies in dem genutzten Internetbrowser, sind unter Umst\u00e4nden nicht alle Funktionen unserer Internetseite vollumf\u00e4nglich nutzbar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Erfassung von allgemeinen Daten und Informationen<\/strong><\/h3>\n\n\n\n<p>Die Internetseite der Arztpraxis Dr. med. Carsten Rottmann erfasst mit jedem Aufruf der Internetseite durch eine betroffene Person oder ein automatisiertes System eine Reihe von allgemeinen Daten und Informationen. Diese allgemeinen Daten und Informationen werden in den Logfiles des Servers gespeichert. Erfasst werden k\u00f6nnen die (1) verwendeten Browsertypen und Versionen, (2) das vom zugreifenden System verwendete Betriebssystem, (3) die Internetseite, von welcher ein zugreifendes System auf unsere Internetseite gelangt (sogenannte Referrer), (4) die Unterwebseiten, welche \u00fcber ein zugreifendes System auf unserer Internetseite angesteuert werden, (5) das Datum und die Uhrzeit eines Zugriffs auf die Internetseite, (6) eine Internet-Protokoll-Adresse (IP-Adresse), (7) der Internet-Service-Provider des zugreifenden Systems und (8) sonstige \u00e4hnliche Daten und Informationen, die der Gefahrenabwehr im Falle von Angriffen auf unsere informationstechnologischen Systeme dienen.<br>Bei der Nutzung dieser allgemeinen Daten und Informationen zieht die Arztpraxis Dr. med. Carsten Rottmann keine R\u00fcckschl\u00fcsse auf die betroffene Person. Diese Informationen werden vielmehr ben\u00f6tigt, um (1) die Inhalte unserer Internetseite korrekt auszuliefern, (2) die Inhalte unserer Internetseite sowie die Werbung f\u00fcr diese zu optimieren, (3) die dauerhafte Funktionsf\u00e4higkeit unserer informationstechnologischen Systeme und der Technik unserer Internetseite zu gew\u00e4hrleisten sowie (4) um Strafverfolgungsbeh\u00f6rden im Falle eines Cyberangriffes die zur Strafverfolgung notwendigen Informationen bereitzustellen. Diese anonym erhobenen Daten und Informationen werden durch die Arztpraxis Dr. med. Carsten Rottmann daher einerseits statistisch und ferner mit dem Ziel ausgewertet, den Datenschutz und die Datensicherheit in unserem Unternehmen zu erh\u00f6hen, um letztlich ein optimales Schutzniveau f\u00fcr die von uns verarbeiteten personenbezogenen Daten sicherzustellen. Die anonymen Daten der Server-Logfiles werden getrennt von allen durch eine betroffene Person angegebenen personenbezogenen Daten gespeichert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Routinem\u00e4\u00dfige L\u00f6schung und Sperrung von personenbezogenen Daten<\/strong><\/h3>\n\n\n\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verarbeitet und speichert personenbezogene Daten der betroffenen Person nur f\u00fcr den Zeitraum, der zur Erreichung des Speicherungszwecks erforderlich ist oder sofern dies durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einen anderen Gesetzgeber in Gesetzen oder Vorschriften, welchen der f\u00fcr die Verarbeitung Verantwortliche unterliegt, vorgesehen wurde.<br>Entf\u00e4llt der Speicherungszweck oder l\u00e4uft eine vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einem anderen zust\u00e4ndigen Gesetzgeber vorgeschriebene Speicherfrist ab, werden die personenbezogenen Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6. Rechte der betroffenen Person<\/strong><\/h3>\n\n\n\n<p>a) Recht auf Best\u00e4tigung<br>Jede betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber einger\u00e4umte Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen eine Best\u00e4tigung dar\u00fcber zu verlangen, ob sie betreffende personenbezogene Daten verarbeitet werden. M\u00f6chte eine betroffene Person dieses Best\u00e4tigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n\n\n\n<p>b) Recht auf Auskunft<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, jederzeit von dem f\u00fcr die Verarbeitung Verantwortlichen unentgeltliche Auskunft \u00fcber die zu seiner Person gespeicherten personenbezogenen Daten und eine Kopie dieser Auskunft zu erhalten. Ferner hat der Europ\u00e4ische Richtlinien- und Verordnungsgeber der betroffenen Person Auskunft \u00fcber folgende Informationen zugestanden:<br>\u2013 die Verarbeitungszwecke<br>\u2013 die Kategorien personenbezogener Daten, die verarbeitet werden<br>\u2013 die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen<br>\u2013 falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer<br>\u2013 das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung<br>\u2013 das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde<br>\u2013 wenn die personenbezogenen Daten nicht bei der betroffenen Person erhoben werden: Alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten<br>\u2013 das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs.1 und 4 DS-GVO und \u2014 zumindest in diesen F\u00e4llen \u2014 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr die betroffene Person.<br>Ferner steht der betroffenen Person ein Auskunftsrecht dar\u00fcber zu, ob personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt wurden. Sofern dies der Fall ist, so steht der betroffenen Person im \u00dcbrigen das Recht zu, Auskunft \u00fcber die geeigneten Garantien im Zusammenhang mit der \u00dcbermittlung zu erhalten.<br>M\u00f6chte eine betroffene Person dieses Auskunftsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n\n\n\n<p>c) Recht auf Berichtigung<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die unverz\u00fcgliche Berichtigung sie betreffender unrichtiger personenbezogener Daten zu verlangen. Ferner steht der betroffenen Person das Recht zu, unter Ber\u00fccksichtigung der Zwecke der Verarbeitung, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2014 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2014 zu verlangen.<br>M\u00f6chte eine betroffene Person dieses Berichtigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n\n\n\n<p>d) Recht auf L\u00f6schung (Recht auf Vergessen werden)<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen zu verlangen, dass die sie betreffenden personenbezogenen Daten unverz\u00fcglich gel\u00f6scht werden, sofern einer der folgenden Gr\u00fcnde zutrifft und soweit die Verarbeitung nicht erforderlich ist:<br>\u2013 Die personenbezogenen Daten wurden f\u00fcr solche Zwecke erhoben oder auf sonstige Weise verarbeitet, f\u00fcr welche sie nicht mehr notwendig sind.<br>\u2013 Die betroffene Person widerruft ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<br>\u2013 Die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 1 DS-GVO Widerspruch gegen die Verarbeitung ein, und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 2 DS-GVO Widerspruch gegen die Verarbeitung ein.<br>\u2013 Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<br>\u2013 Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt.<br>\u2013 Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DS-GVO erhoben.<br>\u2013 Sofern einer der oben genannten Gr\u00fcnde zutrifft und eine betroffene Person die L\u00f6schung von personenbezogenen Daten, die bei der Arztpraxis Dr. med. Carsten Rottmann gespeichert sind, veranlassen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter der Arztpraxis Dr. med. Carsten Rottmann wird veranlassen, dass dem L\u00f6schverlangen unverz\u00fcglich nachgekommen wird.<\/p>\n\n\n\n<p>Wurden die personenbezogenen Daten von der Arztpraxis Dr. med. Carsten Rottmann \u00f6ffentlich gemacht und ist unser Unternehmen als Verantwortlicher gem\u00e4\u00df Art. 17 Abs. 1 DS-GVO zur L\u00f6schung der personenbezogenen Daten verpflichtet, so trifft die Arztpraxis Dr. med. Carsten Rottmann unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um andere f\u00fcr die Datenverarbeitung Verantwortliche, welche die ver\u00f6ffentlichten personenbezogenen Daten verarbeiten, dar\u00fcber in Kenntnis zu setzen, dass die betroffene Person von diesen anderen f\u00fcr die Datenverarbeitung Verantwortlichen die L\u00f6schung s\u00e4mtlicher Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat, soweit die Verarbeitung nicht erforderlich ist. Der Mitarbeiter der Arztpraxis Dr. med. Carsten Rottmann wird im Einzelfall das Notwendige veranlassen.<\/p>\n\n\n\n<p>e) Recht auf Einschr\u00e4nkung der Verarbeitung<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<br>\u2013 Die Richtigkeit der personenbezogenen Daten wird von der betroffenen Person bestritten, und zwar f\u00fcr eine Dauer, die es dem Verantwortlichen erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen.<br>\u2013 Die Verarbeitung ist unrechtm\u00e4\u00dfig, die betroffene Person lehnt die L\u00f6schung der personenbezogenen Daten ab und verlangt stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten.<br>\u2013 Der Verantwortliche ben\u00f6tigt die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger, die betroffene Person ben\u00f6tigt sie jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<br>\u2013 Die betroffene Person hat Widerspruch gegen die Verarbeitung gem. Art. 21 Abs. 1 DS-GVO eingelegt und es steht noch nicht fest, ob die berechtigten Gr\u00fcnde des Verantwortlichen gegen\u00fcber denen der betroffenen Person \u00fcberwiegen.<\/p>\n\n\n\n<p>Sofern eine der oben genannten Voraussetzungen gegeben ist und eine betroffene Person die Einschr\u00e4nkung von personenbezogenen Daten, die bei der Arztpraxis Dr. med. Carsten Rottmann gespeichert sind, verlangen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter der Arztpraxis Dr. med. Carsten Rottmann wird die Einschr\u00e4nkung der Verarbeitung veranlassen.<\/p>\n\n\n\n<p>f) Recht auf Daten\u00fcbertragbarkeit<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die sie betreffenden personenbezogenen Daten, welche durch die betroffene Person einem Verantwortlichen bereitgestellt wurden, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Sie hat au\u00dferdem das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch den Verantwortlichen, dem die personenbezogenen Daten bereitgestellt wurden, zu \u00fcbermitteln, sofern die Verarbeitung auf der Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DS-GVO oder Art. 9 Abs. 2 Buchstabe a DS-GVO oder auf einem Vertrag gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe b DS-GVO beruht und die Verarbeitung mithilfe automatisierter Verfahren erfolgt, sofern die Verarbeitung nicht f\u00fcr die Wahrnehmung einer Aufgabe erforderlich ist, die im \u00f6ffentlichen Interesse liegt oder in Aus\u00fcbung \u00f6ffentlicher Gewalt erfolgt, welche dem Verantwortlichen \u00fcbertragen wurde.<br>Ferner hat die betroffene Person bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Art. 20 Abs. 1 DS-GVO das Recht, zu erwirken, dass die personenbezogenen Daten direkt von einem Verantwortlichen an einen anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist und sofern hiervon nicht die Rechte und Freiheiten anderer Personen beeintr\u00e4chtigt werden.<br>Zur Geltendmachung des Rechts auf Daten\u00fcbertragbarkeit kann sich die betroffene Person jederzeit an einen Mitarbeiter der Arztpraxis Dr. med. Carsten Rottmann wenden.<\/p>\n\n\n\n<p>g) Recht auf Widerspruch<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Art. 6 Abs. 1 Buchstaben e oder f DS-GVO erfolgt, Widerspruch einzulegen. Dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<br>Die Arztpraxis Dr. med. Carsten Rottmann verarbeitet die personenbezogenen Daten im Falle des Widerspruchs nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die den Interessen, Rechten und Freiheiten der betroffenen Person \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<br>Verarbeitet die Arztpraxis Dr. med. Carsten Rottmann personenbezogene Daten, um Direktwerbung zu betreiben, so hat die betroffene Person das Recht, jederzeit Widerspruch gegen die Verarbeitung der personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen. Dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widerspricht die betroffene Person gegen\u00fcber der Arztpraxis Dr. med. Carsten Rottmann der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so wird die Arztpraxis Dr. med. Carsten Rottmann die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeiten.<br>Zudem hat die betroffene Person das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die sie betreffende Verarbeitung personenbezogener Daten, die bei der Arztpraxis Dr. med. Carsten Rottmann zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Art. 89 Abs. 1 DS-GVO erfolgen, Widerspruch einzulegen, es sei denn, eine solche Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich.<br>Zur Aus\u00fcbung des Rechts auf Widerspruch kann sich die betroffene Person direkt jeden Mitarbeiter der Arztpraxis Dr. med. Carsten Rottmann oder einen anderen Mitarbeiter wenden. Der betroffenen Person steht es ferner frei, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft, ungeachtet der Richtlinie 2002\/58\/EG, ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden.<\/p>\n\n\n\n<p>h) Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2014 einschlie\u00dflich Profiling \u2014 beruhenden Entscheidung unterworfen zu werden, die ihr gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt, sofern die Entscheidung (1) nicht f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich ist, oder (2) aufgrund von Rechtsvorschriften der Union oder der Mitgliedstaaten, denen der Verantwortliche unterliegt, zul\u00e4ssig ist und diese Rechtsvorschriften angemessene Ma\u00dfnahmen zur Wahrung der Rechte und Freiheiten sowie der berechtigten Interessen der betroffenen Person enthalten oder (3) mit ausdr\u00fccklicher Einwilligung der betroffenen Person erfolgt.<br>Ist die Entscheidung (1) f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich oder (2) erfolgt sie mit ausdr\u00fccklicher Einwilligung der betroffenen Person, trifft die Arztpraxis Dr. med. Martin Noelke und Waldemar H. Saeger angemessene Ma\u00dfnahmen, um die Rechte und Freiheiten sowie die berechtigten Interessen der betroffenen Person zu wahren, wozu mindestens das Recht auf Erwirkung des Eingreifens einer Person seitens des Verantwortlichen, auf Darlegung des eigenen Standpunkts und auf Anfechtung der Entscheidung geh\u00f6rt.<br>M\u00f6chte die betroffene Person Rechte mit Bezug auf automatisierte Entscheidungen geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<br>i) Recht auf Widerruf einer datenschutzrechtlichen Einwilligung<br>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen.<br>M\u00f6chte die betroffene Person ihr Recht auf Widerruf einer Einwilligung geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7. Datenschutz bei Bewerbungen und im Bewerbungsverfahren<\/strong><\/h3>\n\n\n\n<p>Der f\u00fcr die Verarbeitung Verantwortliche erhebt und verarbeitet die personenbezogenen Daten von Bewerbern zum Zwecke der Abwicklung des Bewerbungsverfahrens. Die Verarbeitung kann auch auf elektronischem Wege erfolgen. Dies ist insbesondere dann der Fall, wenn ein Bewerber entsprechende Bewerbungsunterlagen auf dem elektronischen Wege, beispielsweise per E-Mail oder \u00fcber ein auf der Internetseite befindliches Webformular, an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelt. Schlie\u00dft der f\u00fcr die Verarbeitung Verantwortliche einen Anstellungsvertrag mit einem Bewerber, werden die \u00fcbermittelten Daten zum Zwecke der Abwicklung des Besch\u00e4ftigungsverh\u00e4ltnisses unter Beachtung der gesetzlichen Vorschriften gespeichert. Wird von dem f\u00fcr die Verarbeitung Verantwortlichen kein Anstellungsvertrag mit dem Bewerber geschlossen, so werden die Bewerbungsunterlagen zwei Monate nach Bekanntgabe der Absageentscheidung automatisch gel\u00f6scht, sofern einer L\u00f6schung keine sonstigen berechtigten Interessen des f\u00fcr die Verarbeitung Verantwortlichen entgegenstehen. Sonstiges berechtigtes Interesse in diesem Sinne ist beispielsweise eine Beweispflicht in einem Verfahren nach dem Allgemeinen Gleichbehandlungsgesetz (AGG).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>8. Datenschutzbestimmungen zu Einsatz und Verwendung von Google Analytics (mit Anonymisierungsfunktion)<\/strong><\/h3>\n\n\n\n<p>Der f\u00fcr die Verarbeitung Verantwortliche hat auf dieser Internetseite die Komponente Google Analytics (mit Anonymisierungsfunktion) integriert. Google Analytics ist ein Web-Analyse-Dienst. Web-Analyse ist die Erhebung, Sammlung und Auswertung von Daten \u00fcber das Verhalten von Besuchern von Internetseiten. Ein Web-Analyse-Dienst erfasst unter anderem Daten dar\u00fcber, von welcher Internetseite eine betroffene Person auf eine Internetseite gekommen ist (sogenannte Referrer), auf welche Unterseiten der Internetseite zugegriffen oder wie oft und f\u00fcr welche Verweildauer eine Unterseite betrachtet wurde. Eine Web-Analyse wird \u00fcberwiegend zur Optimierung einer Internetseite und zur Kosten-Nutzen-Analyse von Internetwerbung eingesetzt.<br>Betreibergesellschaft der Google-Analytics-Komponente ist die Google Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.<br>Der f\u00fcr die Verarbeitung Verantwortliche verwendet f\u00fcr die Web-Analyse \u00fcber Google Analytics den Zusatz \u201e_gat._anonymizeIp\u201c. Mittels dieses Zusatzes wird die IP-Adresse des Internetanschlusses der betroffenen Person von Google gek\u00fcrzt und anonymisiert, wenn der Zugriff auf unsere Internetseiten aus einem Mitgliedstaat der Europ\u00e4ischen Union oder aus einem anderen Vertragsstaat des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum erfolgt.<br>Der Zweck der Google-Analytics-Komponente ist die Analyse der Besucherstr\u00f6me auf unserer Internetseite. Google nutzt die gewonnenen Daten und Informationen unter anderem dazu, die Nutzung unserer Internetseite auszuwerten, um f\u00fcr uns Online-Reports, welche die Aktivit\u00e4ten auf unseren Internetseiten aufzeigen, zusammenzustellen, und um weitere mit der Nutzung unserer Internetseite in Verbindung stehende Dienstleistungen zu erbringen.<br>Google Analytics setzt ein Cookie auf dem informationstechnologischen System der betroffenen Person. Was Cookies sind, wurde oben bereits erl\u00e4utert. Mit Setzung des Cookies wird Google eine Analyse der Benutzung unserer Internetseite erm\u00f6glicht. Durch jeden Aufruf einer der Einzelseiten dieser Internetseite, die durch den f\u00fcr die Verarbeitung Verantwortlichen betrieben wird und auf welcher eine Google-Analytics-Komponente integriert wurde, wird der Internetbrowser auf dem informationstechnologischen System der betroffenen Person automatisch durch die jeweilige Google-Analytics-Komponente veranlasst, Daten zum Zwecke der Online-Analyse an Google zu \u00fcbermitteln. Im Rahmen dieses technischen Verfahrens erh\u00e4lt Google Kenntnis \u00fcber personenbezogene Daten, wie der IP-Adresse der betroffenen Person, die Google unter anderem dazu dienen, die Herkunft der Besucher und Klicks nachzuvollziehen und in der Folge Provisionsabrechnungen zu erm\u00f6glichen.<br>Mittels des Cookies werden personenbezogene Informationen, beispielsweise die Zugriffszeit, der Ort, von welchem ein Zugriff ausging und die H\u00e4ufigkeit der Besuche unserer Internetseite durch die betroffene Person, gespeichert. Bei jedem Besuch unserer Internetseiten werden diese personenbezogenen Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.<br>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google ein Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google Analytics bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.<br>Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, einer Erfassung der durch Google Analytics erzeugten, auf eine Nutzung dieser Internetseite bezogenen Daten sowie der Verarbeitung dieser Daten durch Google zu widersprechen und eine solche zu verhindern. Hierzu muss die betroffene Person ein Browser-Add-On unter dem Link https:\/\/tools.google.com\/dlpage\/gaoptout herunterladen und installieren. Dieses Browser-Add-On teilt Google Analytics \u00fcber JavaScript mit, dass keine Daten und Informationen zu den Besuchen von Internetseiten an Google Analytics \u00fcbermittelt werden d\u00fcrfen. Die Installation des Browser-Add-Ons wird von Google als Widerspruch gewertet. Wird das informationstechnologische System der betroffenen Person zu einem sp\u00e4teren Zeitpunkt gel\u00f6scht, formatiert oder neu installiert, muss durch die betroffene Person eine erneute Installation des Browser-Add-Ons erfolgen, um Google Analytics zu deaktivieren. Sofern das Browser-Add-On durch die betroffene Person oder einer anderen Person, die ihrem Machtbereich zuzurechnen ist, deinstalliert oder deaktiviert wird, besteht die M\u00f6glichkeit der Neuinstallation oder der erneuten Aktivierung des Browser-Add-Ons.<br>Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ und unter http:\/\/www.google.com\/analytics\/terms\/de.html abgerufen werden. Google Analytics wird unter diesem Link https:\/\/www.google.com\/intl\/de_de\/analytics\/ genauer erl\u00e4utert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>9. Rechtsgrundlage der Verarbeitung<\/strong><\/h3>\n\n\n\n<p>Art. 6 I lit. a DS-GVO dient unserem Unternehmen als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, bei denen wir eine Einwilligung f\u00fcr einen bestimmten Verarbeitungszweck einholen. Ist die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, erforderlich, wie dies beispielsweise bei Verarbeitungsvorg\u00e4ngen der Fall ist, die f\u00fcr eine Lieferung von Waren oder die Erbringung einer sonstigen Leistung oder Gegenleistung notwendig sind, so beruht die Verarbeitung auf Art. 6 I lit. b DS-GVO. Gleiches gilt f\u00fcr solche Verarbeitungsvorg\u00e4nge die zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich sind, etwa in F\u00e4llen von Anfragen zur unseren Produkten oder Leistungen. Unterliegt unser Unternehmen einer rechtlichen Verpflichtung durch welche eine Verarbeitung von personenbezogenen Daten erforderlich wird, wie beispielsweise zur Erf\u00fcllung steuerlicher Pflichten, so basiert die Verarbeitung auf Art. 6 I lit. c DS-GVO. In seltenen F\u00e4llen k\u00f6nnte die Verarbeitung von personenbezogenen Daten erforderlich werden, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen. Dies w\u00e4re beispielsweise der Fall, wenn ein Besucher in unserem Betrieb verletzt werden w\u00fcrde und daraufhin sein Name, sein Alter, seine Krankenkassendaten oder sonstige lebenswichtige Informationen an einen Arzt, ein Krankenhaus oder sonstige Dritte weitergegeben werden m\u00fcssten. Dann w\u00fcrde die Verarbeitung auf Art. 6 I lit. d DS-GVO beruhen. Letztlich k\u00f6nnten Verarbeitungsvorg\u00e4nge auf Art. 6 I lit. f DS-GVO beruhen. Auf dieser Rechtsgrundlage basieren Verarbeitungsvorg\u00e4nge, die von keiner der vorgenannten Rechtsgrundlagen erfasst werden, wenn die Verarbeitung zur Wahrung eines berechtigten Interesses unseres Unternehmens oder eines Dritten erforderlich ist, sofern die Interessen, Grundrechte und Grundfreiheiten des Betroffenen nicht \u00fcberwiegen. Solche Verarbeitungsvorg\u00e4nge sind uns insbesondere deshalb gestattet, weil sie durch den Europ\u00e4ischen Gesetzgeber besonders erw\u00e4hnt wurden. Er vertrat insoweit die Auffassung, dass ein berechtigtes Interesse anzunehmen sein k\u00f6nnte, wenn die betroffene Person ein Kunde des Verantwortlichen ist (Erw\u00e4gungsgrund 47 Satz 2 DS-GVO).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>10. Berechtigte Interessen an der Verarbeitung, die von dem Verantwortlichen oder einem Dritten verfolgt werden<\/strong><\/h3>\n\n\n\n<p>Basiert die Verarbeitung personenbezogener Daten auf Artikel 6 I lit. f DS-GVO ist unser berechtigtes Interesse die Durchf\u00fchrung unserer Gesch\u00e4ftst\u00e4tigkeit zugunsten des Wohlergehens all unserer Mitarbeiter und unserer Anteilseigner.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>11. Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden<\/strong><\/h3>\n\n\n\n<p>Das Kriterium f\u00fcr die Dauer der Speicherung von personenbezogenen Daten ist die jeweilige gesetzliche Aufbewahrungsfrist. Nach Ablauf der Frist werden die entsprechenden Daten routinem\u00e4\u00dfig gel\u00f6scht, sofern sie nicht mehr zur Vertragserf\u00fcllung oder Vertragsanbahnung erforderlich sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>12. Gesetzliche oder vertragliche Vorschriften zur Bereitstellung der personenbezogenen Daten; Erforderlichkeit f\u00fcr den Vertragsabschluss; Verpflichtung der betroffenen Person, die personenbezogenen Daten bereitzustellen; m\u00f6gliche Folgen der Nichtbereitstellung<\/strong><\/h3>\n\n\n\n<p>Wir kl\u00e4ren Sie dar\u00fcber auf, dass die Bereitstellung personenbezogener Daten zum Teil gesetzlich vorgeschrieben ist (z.B. Steuervorschriften) oder sich auch aus vertraglichen Regelungen (z.B. Angaben zum Vertragspartner) ergeben kann. Mitunter kann es zu einem Vertragsschluss erforderlich sein, dass eine betroffene Person uns personenbezogene Daten zur Verf\u00fcgung stellt, die in der Folge durch uns verarbeitet werden m\u00fcssen. Die betroffene Person ist beispielsweise verpflichtet uns personenbezogene Daten bereitzustellen, wenn unser Unternehmen mit ihr einen Vertrag abschlie\u00dft. Eine Nichtbereitstellung der personenbezogenen Daten h\u00e4tte zur Folge, dass der Vertrag mit dem Betroffenen nicht geschlossen werden k\u00f6nnte. Vor einer Bereitstellung personenbezogener Daten durch den Betroffenen muss sich der Betroffene an einen unserer Mitarbeiter wenden. Unser Mitarbeiter kl\u00e4rt den Betroffenen einzelfallbezogen dar\u00fcber auf, ob die Bereitstellung der personenbezogenen Daten gesetzlich oder vertraglich vorgeschrieben oder f\u00fcr den Vertragsabschluss erforderlich ist, ob eine Verpflichtung besteht, die personenbezogenen Daten bereitzustellen, und welche Folgen die Nichtbereitstellung der personenbezogenen Daten h\u00e4tte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Arztpraxis<\/h2>\n\n\n\n<p><strong>Dr. med. Carsten Rottmann<\/strong><br>Facharzt f\u00fcr Innere Medizin (haus\u00e4rztlich)Dr. med. Christa Uhlich (angestellte \u00c4rztin f. Allgemeinmedizin)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kontakt<\/h2>\n\n\n\n<p>Stadthallenweg 1<br>35315 Homberg\/Ohm<\/p>\n\n\n\n<p>Telefon: 06633 &#8211; 235<br>Telefax: 06633 &#8211; 643515<br>carsten_rottmann@web.de<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Copyright<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Copyright Bilder:<\/td><td>&nbsp; iStockPhoto<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Name und Anschrift: Dr. med. Carsten RottmannStadthallenweg 135315 Homberg\/OhmFon: 06633 \/ 235Fax: 06633 \/ 643515 E-mail-Adresse: hausarzt-homberg@t-online.de \u00c4rztekammer des Arztes: Landes\u00e4rztekammer HessenHanauer Landstra\u00dfe 152, 60314 FrankfurtPostfach 900669, 60446 Frankfurt\/MainTelefon: (069) 97672-0Fax: (069) 97672-128E-Mail: info@laekh.de KV des Arztes: KV Gie\u00dfen eV.Eichg\u00e4rtenallee 90, 35394 Gie\u00dfenTelefon:0641\/400060Telefax:0641\/4000660KV-Nummer: 41 19 019 00 Gesetzliche Berufsbezeichnung: Arzt, verliehen in der Bundesrepublik Deutschland [&hellip;]<\/p>\n","protected":false},"author":653,"featured_media":0,"parent":0,"menu_order":1000,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/users\/653"}],"replies":[{"embeddable":true,"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":13,"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":374,"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/pages\/10\/revisions\/374"}],"wp:attachment":[{"href":"https:\/\/docsites.cgmlife.com\/147325057143\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}